{"id":3468,"date":"2021-08-31T15:51:00","date_gmt":"2021-08-31T14:51:00","guid":{"rendered":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/?p=3468"},"modified":"2025-07-18T14:03:41","modified_gmt":"2025-07-18T13:03:41","slug":"comment-assister-a-la-grande-migration-des-gnous-en-afrique-de-lest","status":"publish","type":"post","link":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/comment-assister-a-la-grande-migration-des-gnous-en-afrique-de-lest\/","title":{"rendered":"Comment assister \u00e0 la grande migration des gnous en Afrique de l\u2019Est ?"},"content":{"rendered":"\n<p>Peut-\u00eatre connaissez-vous ces images impressionnantes repr\u00e9sentant des milliers de gnous parcourant les plaines de la Tanzanie \u00e0 la recherche de verts p\u00e2turages ? Ou encore celles de leur p\u00e9rilleuse travers\u00e9e de la rivi\u00e8re Mara, jusqu\u2019au Kenya&#8230; Cette gigantesque migration d\u2019herbivores regroupe des gnous mais aussi des z\u00e8bres, quelques gazelles et impalas, suivis de pr\u00e8s par leurs pr\u00e9dateurs. Il s\u2019agit d\u2019un ph\u00e9nom\u00e8ne qui a lieu chaque ann\u00e9e depuis des millions d\u2019ann\u00e9es\u2026 mais dont le calendrier reste al\u00e9atoire : il peut varier de quelques semaines, en fonction de la saison des pluies.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>De quoi s\u2019agit-il et comment assister \u00e0 ce spectacle saisissant et unique au monde ? Voici nos conseils pour mettre toutes les chances de votre c\u00f4t\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-1.jpg\" alt=\"\" class=\"wp-image-3469\" width=\"800\" height=\"600\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-1.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-1-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Gnous traversant la rivi\u00e8re Mara<\/figcaption><\/figure>\n\n\n\n<h2><strong>Un impressionnant troupeau en route pour plus de 1000 km<\/strong> <strong>de marche<\/strong><\/h2>\n\n\n\n<p>Chaque ann\u00e9e au mois de novembre, les pluies arrosent les plaines africaines de Tanzanie. L\u2019herbe y est verte et abondante jusqu\u2019au mois de f\u00e9vrier, et les gnous ont de quoi se sustenter. Les femelles, bien nourries, peuvent allaiter et en profitent pour mettre bas. C\u2019est \u00e0 cette p\u00e9riode que les animaux commencent \u00e0 se regrouper dans la zone du crat\u00e8re du N\u2019Gorongoro et de N\u2019Dutu. Se forme ainsi un impressionnant troupeau d\u2019environ 2 millions de gnous et 500 000 z\u00e8bres\u2026 C\u2019est le d\u00e9but de la Grande Migration. Les plaines de N\u2019Dutu sont alors enti\u00e8rement recouvertes de gnous et offrent des images fascinantes&#8230; Les animaux marchent souvent \u00e0 la queue leu leu, formant une longue colonne allant parfois jusqu\u2019\u00e0 40 km.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-2.jpg\" alt=\"\" class=\"wp-image-3470\" width=\"800\" height=\"600\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-2.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-2-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-2-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Troupeau de gnous marchant \u00e0 la queue leu leu<\/figcaption><\/figure>\n\n\n\n<p>Aux alentours du mois de mars, la s\u00e9cheresse arrivant, le troupeau se d\u00e9place en qu\u00eate de nouveaux p\u00e2turages et se dirige vers l\u2019immense plaine du Serengeti, au Nord de la Tanzanie.<\/p>\n\n\n\n<p>A partir du mois de juillet s\u2019annonce une \u00e9tape d\u00e9cisive : la travers\u00e9e de la rivi\u00e8re Mara, fronti\u00e8re naturelle qui s\u00e9pare la Tanzanie du Kenya et qui ouvre la voie vers les vertes \u00e9tendues du Masa\u00ef Mara. Une \u00e9tape p\u00e9rilleuse o\u00f9 de nombreux dangers guettent les gnous, en particulier les \u00e9normes crocodiles du Nil qui attendent, tapis dans la rivi\u00e8re\u2026&nbsp; La travers\u00e9e n\u2019est pas facile et beaucoup p\u00e9riront face aux pr\u00e9dateurs ou en tombant et se cassant les pattes sur les rives escarp\u00e9es de la rivi\u00e8re.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-3-1.jpg\" alt=\"\" class=\"wp-image-3472\" width=\"800\" height=\"377\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-3-1.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-3-1-300x141.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-3-1-768x362.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Gnous se jetant des rives escarp\u00e9es de la rivi\u00e8re Mara<\/figcaption><\/figure>\n\n\n\n<p>Une fois la rivi\u00e8re franchie, les gnous s\u2019installent dans le Masa\u00ef Mara jusqu\u2019au mois d\u2019octobre: c\u2019est la fin du cycle de la migration.<\/p>\n\n\n\n<p>Chaque ann\u00e9e, les troupeaux parcourent plus de 1000 km.&nbsp;Tous les gnous ne migrent pas, mais les trois quarts d\u2019entre eux d\u00e9cident de partir, certains ne faisant qu\u2019une partie du voyage. Beaucoup ne termineront pas le parcours, mourront d\u2019\u00e9puisement ou seront la proie des lions, l\u00e9opards, crocodiles et autres pr\u00e9dateurs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-4.jpg\" alt=\"\" class=\"wp-image-3473\" width=\"800\" height=\"512\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-4.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-4-300x192.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-4-768x492.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Travers\u00e9e de la rivi\u00e8re par les troupeaux de gnous et de z\u00e8bres<\/figcaption><\/figure>\n\n\n\n<h2><strong>\u00catre t\u00e9moin de la grande migration<\/strong><\/h2>\n\n\n\n<p>Comment ne pas \u00eatre tent\u00e9 d\u2019approcher au plus pr\u00e8s ce ph\u00e9nom\u00e8ne unique au monde ? Cependant, personne ne peut anticiper au jour pr\u00e8s l\u2019arriv\u00e9e des gnous dans les plaines de N\u2019Dutu ou au bord de la rivi\u00e8re Mara. La patience sera votre plus grande alli\u00e9e, et il faudra pr\u00e9voir plusieurs jours de voyage dans la savane pour tenter de vivre cette exp\u00e9rience incomparable.<\/p>\n\n\n\n<p>Deux options s\u2019offrent \u00e0 vous:<\/p>\n\n\n\n<ul><li>Pr\u00e9voyez de passer environ 4 jours <a href=\"https:\/\/www.makila.fr\/hotels\/456-lac-ndutu-luxury-tented-camp-n-dutu\" class=\"broken_link\">dans un camp de la r\u00e9gion de N\u2019Dutu<\/a> o\u00f9 vous aurez toutes les chances de voir passer les gigantesques troupeaux de gnous et de z\u00e8bres, et d\u2019assister \u00e0 un \u00e9v\u00e9nement hors-du-commun, celui de la naissance de b\u00e9b\u00e9s gnous.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-5.jpg\" alt=\"\" class=\"wp-image-3474\" width=\"800\" height=\"501\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-5.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-5-300x188.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-5-768x481.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Gnous couvrant les plaines du N\u2019Dutu<\/figcaption><\/figure>\n\n\n\n<ul><li>Choisissez un camp au c\u0153ur de Masa\u00ef Mara, <a href=\"https:\/\/www.makila.fr\/hotels\/492-naibor-camp-masai-mara\">comme le Naibor Camp<\/a> pr\u00e8s de la rivi\u00e8re Mara, o\u00f9 vous pourrez vous installer plusieurs jours en attendant le passage du troupeau, observer le spectacle unique de ces milliers de gnous franchissant la rivi\u00e8re et vous laisser impr\u00e9gner par ce sentiment d\u2019immensit\u00e9 que seule peut offrir la nature africaine.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-6.jpg\" alt=\"\" class=\"wp-image-3475\" width=\"800\" height=\"446\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-6.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-6-300x167.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2021\/09\/La-grande-migration-des-gnous_V2-6-768x428.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Vue du passage des gnous sur la rivi\u00e8re Mara depuis le camp de toile de Singita<\/figcaption><\/figure>\n\n\n\n<p>Votre s\u00e9jour dans un camp au bord de la rivi\u00e8re Mara ou \u00e0 N\u2019Dutu s&rsquo;inscrit ais\u00e9ment dans le cadre d\u2019un plus long voyage. Vous pouvez y coupler <a href=\"https:\/\/www.makila.fr\/voyages\/27-safari-en-tanzanie-manyara-serengeti-ngorongoro-tarangire\">un safari en Tanzanie<\/a> ou <a href=\"https:\/\/www.makila.fr\/voyages\/31-de-samburu-a-masai-mara-en-passant-par-la-rift-valley\">au Kenya<\/a>, ou encore quelques jours <a href=\"https:\/\/www.makila.fr\/voyages\/277-combine-tanzanie-zanzibar-beaute-sauvage-et-plages-de-reve\">\u00e0 Zanzibar<\/a> pour profiter d\u2019une mer chaude apr\u00e8s votre escapade en pleine nature&#8230;<\/p>\n\n\n\n<p>N\u2019h\u00e9sitez pas \u00e0 nous solliciter pour en savoir plus, et si vous souhaitez vous renseigner sur les autres ph\u00e9nom\u00e8nes migratoires que l\u2019on peut observer en Afrique : la migration des z\u00e8bres au Botswana, ou encore celle des chauve-souris en Zambie&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peut-\u00eatre connaissez-vous ces images impressionnantes repr\u00e9sentant des milliers de gnous parcourant les plaines de la Tanzanie \u00e0 la recherche de verts p\u00e2turages ? Ou encore celles de leur p\u00e9rilleuse travers\u00e9e de la rivi\u00e8re Mara, jusqu\u2019au Kenya&#8230; Cette gigantesque migration d\u2019herbivores regroupe des gnous mais aussi des z\u00e8bres, quelques gazelles et impalas, suivis de pr\u00e8s par [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3469,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[146,1,4],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3468"}],"collection":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":7,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"predecessor-version":[{"id":4321,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3468\/revisions\/4321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media\/3469"}],"wp:attachment":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}