{"id":33,"date":"2011-10-20T23:07:00","date_gmt":"2011-10-20T22:07:00","guid":{"rendered":"http:\/\/www.makila.fr\/blog\/voyage-sur-mesure\/?p=33"},"modified":"2024-10-22T16:54:48","modified_gmt":"2024-10-22T15:54:48","slug":"wilderness-safaris-et-makila-coeur-et-ame","status":"publish","type":"post","link":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wilderness-safaris-et-makila-coeur-et-ame\/","title":{"rendered":"Wilderness Safaris et Makila, partenaires de coeur et d&rsquo;\u00e2me"},"content":{"rendered":"<div style=\"font-family: inherit; text-align: justify;\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2011\/10\/wilderness-safaris.png\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-249\" title=\"wilderness-safaris\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2011\/10\/wilderness-safaris.png\" alt=\"Logo Wilderness Safaris\" width=\"150\" height=\"100\"><\/a><a href=\"http:\/\/www.wilderness-safaris.com\/\">Wilderness Safaris<\/a>&nbsp;est l\u2019un des plus grands op\u00e9rateurs de voyages d\u2019Afrique australe. <strong>Wilderness Safaris, c\u2019est plus de 50 lodges ou camps en Afrique et aux Seychelles.<\/strong> Autant d\u2019h\u00e9bergements de grand charme qui s\u2019int\u00e8grent \u00e0 l\u2019environnement, chacun \u00e9tant unique. Du simple camp de toile au lodge luxueux, l\u2019accueil y est toujours soign\u00e9, chaleureux et attentionn\u00e9. Wilderness Safaris s\u2019efforce de proposer une offre large pour tous les go\u00fbts et presque tous les budgets.<br \/>\n<!--more--><\/p>\n<h2>Parmi les lodges et camps Wilderness<\/h2>\n<p>On adore tous les h\u00e9bergements de Wilderness, cependant parmi nos chouchous, citons <a href=\"http:\/\/www.makila.fr\/hotels\/43-okavango-camps-mombo-camp\">Mombo Camp<\/a>, <a href=\"http:\/\/www.makila.fr\/hotels\/39-okavango-camps-le-camp-de-jao\">Jao Camp<\/a> ou <a href=\"http:\/\/www.makila.fr\/hotels\/46-okavango-camps-le-camp-de-vumbura-plain\">Vumbura Camp au Botswana<\/a>, <a href=\"http:\/\/www.makila.fr\/hotels\/80-little-kulala\">Little Kulala desert lodge<\/a> et <a href=\"http:\/\/www.makila.fr\/hotels\/90-serra-cafema\">Serra Cafema en Namibie<\/a>, et bien s\u00fbr l\u2019exceptionnel <a href=\"http:\/\/www.makila.fr\/hotels\/201-north-island\">North Island Lodge aux Seychelles<\/a>. Aussi pr\u00e9sents en Zambie, Zimbabwe, Mozambique, Malawi et Afrique du Sud et au Congo.<\/p>\n<h2>Une histoire et des valeurs partag\u00e9es<\/h2>\n<p>Andy Egginton, directeur de la production de Makila, f\u00fbt l\u2019un des pionniers de Wilderness Safaris. Notre coop\u00e9ration fiable depuis pr\u00e8s de 20 ans, nous a valu le titre partenaire de coeur et d\u2019\u00e2me, Heart and Soul, car nous partageons les m\u00eames valeurs :<\/p>\n<ul>\n<li>Un engagement fort pour la protection de la nature, des hommes et des animaux qui y vivent (cf <a href=\"http:\/\/www.childreninthewilderness.com\/\" class=\"broken_link\">Children in the Wilderness<\/a>).<\/li>\n<li>Le d\u00e9veloppement d\u2019une activit\u00e9 <a href=\"http:\/\/fr.wilderness-safaris.com\/sustainability\" target=\"_blank\" rel=\"noopener\">touristique durable et \u00e9quitable<\/a> de l\u2019Afrique et des pays dans lesquels nous voyageons.<\/li>\n<li>Une volont\u00e9 concr\u00e8te d\u2019int\u00e9grer les populations locales pour un tourisme toujours plus \u00e9cologique. Le <a href=\"http:\/\/www.wildernesstrust.com\/\" target=\"_blank\" rel=\"noopener\">Wilderness Wildlife Trust<\/a> en est la d\u00e9monstration.<\/li>\n<li>Le sens de l\u2019accueil et la qualit\u00e9 des prestations propos\u00e9s.<\/li>\n<\/ul>\n<h2>Votre avantage<\/h2>\n<p>Ainsi, <strong>nous pouvons proposer, des prestations hors pairs aussi bien en terme de prix que de qualit\u00e9 de service, sans interm\u00e9diaire<\/strong>; cela nous procure une totale libert\u00e9 dans la cr\u00e9ation de vos voyages sur mesure. <strong>Nous avons acc\u00e8s&nbsp;<\/strong><strong style=\"font-family: inherit;\">en temps r\u00e9el<\/strong><strong style=\"font-family: inherit;\">&nbsp;\u00e0 la disponibilit\u00e9 de tous les camps de Wilderness Safaris<\/strong><span style=\"font-family: inherit;\">&nbsp;par un syst\u00e8me mit en place entre de Wilderness Safaris &nbsp;et nous Makila.<\/span><\/p>\n<p>En lire plus sur <a href=\"http:\/\/fr.wilderness-safaris.com\/sustainability\">le partenariat entre Makila et Wilderness Safaris<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wilderness Safaris&nbsp;est l\u2019un des plus grands op\u00e9rateurs de voyages d\u2019Afrique australe. Wilderness Safaris, c\u2019est plus de 50 lodges ou camps en Afrique et aux Seychelles. Autant d\u2019h\u00e9bergements de grand charme qui s\u2019int\u00e8grent \u00e0 l\u2019environnement, chacun \u00e9tant unique. Du simple camp de toile au lodge luxueux, l\u2019accueil y est toujours soign\u00e9, chaleureux et attentionn\u00e9. Wilderness Safaris [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1,4],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/33"}],"collection":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":6,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"predecessor-version":[{"id":2768,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/33\/revisions\/2768"}],"wp:attachment":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}