{"id":3181,"date":"2020-07-10T14:00:36","date_gmt":"2020-07-10T13:00:36","guid":{"rendered":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/?p=3181"},"modified":"2024-10-22T16:54:30","modified_gmt":"2024-10-22T15:54:30","slug":"laure-lambusson","status":"publish","type":"post","link":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/laure-lambusson\/","title":{"rendered":"Laure Lambusson, sp\u00e9cialiste de l\u2019Afrique de l\u2019Est, de l\u2019Afrique australe  et de Madagascar : le voyage par les sens"},"content":{"rendered":"\n<p align=\"justify\">Le soleil darde ses derniers rayons sur le paisible d\u00e9sert. Laure contemple ce magnifique spectacle, berc\u00e9e par une douce brise qui caresse son visage. Elle se rem\u00e9more sa merveilleuse journ\u00e9e de marche dans les dunes color\u00e9es du Namib, au milieu des oryx et des taupes dor\u00e9es. Elle respire profond\u00e9ment, s\u2019impr\u00e8gne de la qui\u00e9tude des lieux, puis s\u2019allonge sur son lit de camp pour observer les premi\u00e8res \u00e9toiles qui s\u2019allument dans le ciel africain. Seule au monde, elle profite de ces instants pr\u00e9cieux avant de sombrer dans un sommeil profond et r\u00e9parateur.<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Sossusvlei-\u00ae-L.Lambusson-Mai-2013.jpg\" alt=\"\" class=\"wp-image-3189\" width=\"800\" height=\"600\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Sossusvlei-\u00ae-L.Lambusson-Mai-2013.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Sossusvlei-\u00ae-L.Lambusson-Mai-2013-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Sossusvlei-\u00ae-L.Lambusson-Mai-2013-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Dunes de Sossusvlei, d\u00e9sert du Namib<\/figcaption><\/figure>\n\n\n\n<p align=\"justify\">Du haut de ses dix ans, Laure se prenait d\u00e9j\u00e0 \u00e0 r\u00eaver devant les images du T\u00e9n\u00e9r\u00e9, faisant le voeu d\u2019aller un jour rencontrer les Touaregs. Sa volont\u00e9 de voyager et de d\u00e9couvrir les d\u00e9serts du monde ne faiblit pas en grandissant. Depuis, une passion pour les espaces infinis est n\u00e9e, qui ne l\u2019a jamais quitt\u00e9e.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2><strong>L\u2019Afrique de bout en bout<\/strong><\/h2>\n\n\n\n<p align=\"justify\">Apr\u00e8s des \u00e9tudes de marketing, Laure suit un Master sp\u00e9cialis\u00e9 en commerce international et effectue son stage de fin d\u2019\u00e9tudes chez le tour op\u00e9rateur Out Of Africa. Elle y d\u00e9couvre d\u2019abord l\u2019Afrique du Nord et de l\u2019Ouest, notamment l\u2019Egypte et le Sierra Leone. Embauch\u00e9e \u00e0 l\u2019issue de son stage, elle touche \u00e0 d\u2019autres destinations en Am\u00e9rique latine et en Asie, avant de d\u00e9cider de se consacrer uniquement \u00e0 l\u2019Afrique.&nbsp;<\/p>\n\n\n\n<p align=\"justify\">Alors que son agence Out of Africa est rachet\u00e9e par Comptoir (futur Comptoir des Voyages), elle prend la t\u00eate de Comptoir d\u2019Afrique qui vient de na\u00eetre. Elle y passera 19 ans, pendant lesquels elle parcourra l\u2019Afrique du Nord au Sud et d\u2019Ouest en Est. Quand son directeur l\u2019envoie d\u00e9couvrir le d\u00e9sert du Sahara, c\u2019est une r\u00e9v\u00e9lation. Elle est fascin\u00e9e par cet oc\u00e9an de dunes qu\u2019elle parcourt \u00e0 travers ses voyages au Niger, en Libye et en Alg\u00e9rie, et r\u00e9alise son r\u00eave de jeune fille en rencontrant les populations nomades.<\/p>\n\n\n\n<h2><strong>A la recherche des sensations fortes<\/strong><\/h2>\n\n\n\n<p align=\"justify\">Laure devient une inconditionnelle du sable et des dunes. Elle multiplie les treks, s\u2019enfon\u00e7ant dans le d\u00e9sert en autonomie pendant 15 jours en compagnie d\u2019une amie, d\u2019un guide et de chameliers. Elle d\u00e9couvre plus tard avec autant d\u2019enthousiasme les d\u00e9serts du Namib et du Kalahari en Afrique australe. Envo\u00fbt\u00e9e par les horizons sans limites, elle go\u00fbte ces moments uniques : marcher pieds nus dans le sable doux, prendre le th\u00e9 dans le d\u00e9sert\u2026 Plus que tout au monde, elle aime escalader les grandes dunes de sable, parfois pendant plusieurs heures, transport\u00e9e par le spectacle qui s\u2019offre \u00e0 ses yeux une fois arriv\u00e9e en haut.&nbsp;<\/p>\n\n\n\n<p align=\"justify\">En parall\u00e8le, Laure poursuit ses explorations pour ouvrir de nouvelles destinations au Cameroun, en Guin\u00e9e, au Mali, au Sud-Niger, jusqu\u2019en Afrique de l\u2019Est et en Afrique australe. Son premier safari se d\u00e9roulera au Kenya : ce sera un nouveau coup de coeur. Tr\u00e8s sensible aux ambiances et aux sensations que lui procurent ses voyages, Laure est conquise par la faune et la flore africaines. Elle aime \u00e9teindre le moteur de la voiture et \u00e9couter\u2026 un l\u00e9opard boire dans une flaque d\u2019eau, les \u201cred letchwe\u201d traverser un bras du Delta de l\u2019Okavango\u2026 les bruits et les odeurs des safaris mettent tous ses sens en \u00e9bullition.&nbsp;<\/p>\n\n\n\n<p align=\"justify\">Elle est prise par l\u2019\u00e9motion lorsqu\u2019elle assiste, en Tanzanie, \u00e0 la naissance d\u2019un b\u00e9b\u00e9 gnou jusqu\u2019\u00e0 le voir faire ses premiers pas\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Madagascar-Tsingy-Rouges-Nov-19-\u00aeLaure-Lambusson.jpg\" alt=\"\" class=\"wp-image-3190\" width=\"800\" height=\"600\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Madagascar-Tsingy-Rouges-Nov-19-\u00aeLaure-Lambusson.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Madagascar-Tsingy-Rouges-Nov-19-\u00aeLaure-Lambusson-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Madagascar-Tsingy-Rouges-Nov-19-\u00aeLaure-Lambusson-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Tsingy rouges, Madagascar<\/figcaption><\/figure>\n\n\n\n<p align=\"justify\">Ces exp\u00e9riences lui donneront le go\u00fbt des grandes \u00e9tendues sauvages et des voyages loin de la foule. Peu sensible aux types d\u2019h\u00e9bergements ou \u00e0 leur d\u00e9coration, Laure recherche avant tout le luxe de la tranquillit\u00e9 dans des endroits peu communs o\u00f9 il n\u2019y a pas de monde.&nbsp;<\/p>\n\n\n\n<h2><strong>Le sens du d\u00e9tail et du travail bien fait<\/strong><\/h2>\n\n\n\n<p align=\"justify\">En 2012, Laure est approch\u00e9e par l\u2019agence Monde Authentique qui la s\u00e9duit par sa structure \u00e0 taille humaine et son offre de voyages sur-mesure. En effet, d\u00e9sireuse de satisfaire ses clients, cette formule lui permet de prendre le temps de comprendre leurs besoins et de leur concocter le voyage qu\u2019ils recherchent.&nbsp;<\/p>\n\n\n\n<p align=\"justify\">Quatre ans plus tard, elle est contact\u00e9e par Sylvie Pons qui \u00e9toffe son \u00e9quipe d\u2019experts du sur-mesure sur les destinations africaines. Enthousiaste \u00e0 l\u2019id\u00e9e de rejoindre cette agence \u201c\u00e0 part\u201d et de travailler sur ses destinations de coeur que sont la Tanzanie, le Kenya et le Malawi, elle int\u00e8gre Makila en 2017. Elle devient ainsi la sp\u00e9cialiste de l\u2019Afrique de l\u2019Est, de l\u2019Afrique australe et de Madagascar. M\u00e9thodique, sa pr\u00e9cision est tr\u00e8s appr\u00e9ci\u00e9e par l\u2019\u00e9quipe et ses clients.<\/p>\n\n\n\n<p align=\"justify\">Avis aux voyageurs qui souhaitent courir le monde avec leurs enfants, Laure a une grande exp\u00e9rience en la mati\u00e8re. En effet, m\u00e8re de deux jeunes filles qu\u2019elle a emmen\u00e9es avec elle \u00e0 plusieurs reprises au milieu de la savane, elle saura vous prodiguer ses pr\u00e9cieux conseils afin que votre voyage soit une exp\u00e9rience inoubliable pour toutes les g\u00e9n\u00e9rations.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" src=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Botswana-Delta-de-lOkavango-Oct-18-\u00aeLaure-Lambusson.jpg\" alt=\"\" class=\"wp-image-3191\" width=\"800\" height=\"600\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Botswana-Delta-de-lOkavango-Oct-18-\u00aeLaure-Lambusson.jpg 800w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Botswana-Delta-de-lOkavango-Oct-18-\u00aeLaure-Lambusson-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2020\/07\/Botswana-Delta-de-lOkavango-Oct-18-\u00aeLaure-Lambusson-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>Botswana, Delta de l&rsquo;Okavango<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le soleil darde ses derniers rayons sur le paisible d\u00e9sert. Laure contemple ce magnifique spectacle, berc\u00e9e par une douce brise qui caresse son visage. Elle se rem\u00e9more sa merveilleuse journ\u00e9e de marche dans les dunes color\u00e9es du Namib, au milieu des oryx et des taupes dor\u00e9es. Elle respire profond\u00e9ment, s\u2019impr\u00e8gne de la qui\u00e9tude des lieux, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3189,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3181"}],"collection":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/comments?post=3181"}],"version-history":[{"count":15,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3181\/revisions"}],"predecessor-version":[{"id":3199,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/3181\/revisions\/3199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media\/3189"}],"wp:attachment":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media?parent=3181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/categories?post=3181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/tags?post=3181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}