{"id":21,"date":"2011-12-19T17:30:00","date_gmt":"2011-12-19T16:30:00","guid":{"rendered":"http:\/\/www.makila.fr\/blog\/voyage-sur-mesure\/?p=21"},"modified":"2024-10-22T16:54:46","modified_gmt":"2024-10-22T15:54:46","slug":"noel-en-amerique-latine","status":"publish","type":"post","link":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/noel-en-amerique-latine\/","title":{"rendered":"No\u00ebl en Am\u00e9rique latine"},"content":{"rendered":"<div><\/div>\n<div style=\"text-align: justify;\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/noel-en-amerique-latine.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-102 alignleft\" title=\"noel en amerique latine\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/noel-en-amerique-latine-300x214.jpg\" alt=\"noel en amerique latine\" width=\"300\" height=\"214\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/noel-en-amerique-latine-300x214.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/noel-en-amerique-latine.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Llego la Navidad ! Des terres Mexicaines \u00e0 la Terre de Feu, la tradition de No\u00ebl import\u00e9e par les espagnols et les portugais m\u00e9lange rites catholiques et traditions pr\u00e9colombiennes, le tout dans la bonne humeur avec de la musique omni-pr\u00e9sente, des plats traditionnels et pour beaucoup l\u2019occasion de se retrouver en famille.<\/div>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">En d\u00e9cembre, c\u2019est l\u2019\u00e9t\u00e9 partout, sous 30\u00b0 des boules en coton feront office de neige et les sapins sont en plastique \u2026 mais peu importe pourvu que tout le monde soit r\u00e9uni. On compte autant de cr\u00e8ches que de villages de toutes sortes : de la grosse cr\u00e8che install\u00e9e contre un immeuble d&rsquo;affaires \u00e0 la tr\u00e8s kitch petite cr\u00e8che artisanale en bois, en laine de lama, en terre cuite, en p\u00e2te \u00e0 sel ou m\u00eame en sucre ! Pour certaines elles seront en allumettes, en ferraille et autres \u00e9l\u00e9ments de r\u00e9cup\u00e9ration. Tr\u00e8s pittoresques, celles du <a href=\"http:\/\/www.makila.fr\/voyages\/pays\/33-guatemala\">Guatemala<\/a> avec des villages, des lacs et des montagnes compos\u00e9s de brins de camomille, mousses, lichens,&nbsp; sciure de pin teintes.<\/div>\n<div>\n<div id=\"attachment_100\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Creche-de-Noel-au-Guatemala.jpg\"><img aria-describedby=\"caption-attachment-100\" loading=\"lazy\" class=\"size-medium wp-image-100\" title=\"Creche de Noel au Guatemala\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Creche-de-Noel-au-Guatemala-300x225.jpg\" alt=\"Creche de Noel au Guatemala\" width=\"300\" height=\"225\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Creche-de-Noel-au-Guatemala-300x225.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Creche-de-Noel-au-Guatemala.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-100\" class=\"wp-caption-text\">Cr\u00e8che de No\u00ebl au Guatemala<\/p><\/div>\n<\/div>\n<div><\/div>\n<div>\n<div style=\"text-align: justify;\">En <a href=\"http:\/\/www.makila.fr\/voyages\/pays\/22-argentine\">Argentine,<\/a> des arbres de No\u00ebl constitu\u00e9s de mat\u00e9riaux recycl\u00e9s ont \u00e9t\u00e9 install\u00e9s dans le parc de No\u00ebl sur la place des Nations Unies \u00e0 Buenos Aires pour sensibiliser la population \u00e0 la protection de l&rsquo;environnement. Un cadeau de no\u00ebl \u00e0 la plan\u00e8te!<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Au <a href=\"http:\/\/www.makila.fr\/voyages\/pays\/35-mexique\">Mexique<\/a>, s\u2019appuyant sur la date de naissance du dieu v\u00e9n\u00e9r\u00e9 par les Azt\u00e8ques : Huitzilopochtli, qui co\u00efncide avec les f\u00eates chr\u00e9tiennes, des moines augustins auraient, semble t-il, inaugur\u00e9 le rite des processions et notamment celle des Posadas qui se poursuit&nbsp; encore aujourd\u2019hui : un groupe de gens va de maison en maison en chantant dans la rue, cela repr\u00e9sente la qu\u00eate de Marie et Joseph pour trouver un toit o\u00f9 donner naissance \u00e0 J\u00e9sus \u2026.. et \u00e7a marche ! L\u2019accueil dans chaque maison est toujours chaleureux et les veill\u00e9es sont toujours tr\u00e8s gaies.<\/div>\n<div>\n<div id=\"attachment_101\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-au-Mexique.jpg\"><img aria-describedby=\"caption-attachment-101\" loading=\"lazy\" class=\"size-medium wp-image-101\" title=\"Noel au Mexique\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-au-Mexique-300x226.jpg\" alt=\"Noel au Mexique\" width=\"300\" height=\"226\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-au-Mexique-300x226.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-au-Mexique.jpg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-101\" class=\"wp-caption-text\">F\u00eate de No\u00ebl au Mexique<\/p><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">En <a href=\"http:\/\/www.makila.fr\/voyages\/pays\/27-colombie\">Colombie<\/a>, \u00e0 Medellin, la rivi\u00e8re se rev\u00eat de mille et une lumi\u00e8res, tout une mise en sc\u00e8ne de personnages et de symboles de la ville, \u00e7a d\u00e9marre par un concert, on se balade le long de la rivi\u00e8re \u00e0 pied ou dans une traditionnelle \u00ab chiva \u00bb petit minibus aux peintures color\u00e9es, et cette ann\u00e9e l\u2019accent est port\u00e9 sur une r\u00e9flexion sur l\u2019environnement, le tout \u00ab con sabor a jazz, salsa, cumbia y joropo \u00bb !<\/p>\n<div id=\"attachment_103\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-en-Colombie.jpg\"><img aria-describedby=\"caption-attachment-103\" loading=\"lazy\" class=\"size-medium wp-image-103\" title=\"Noel en Colombie\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-en-Colombie-300x199.jpg\" alt=\"Noel en Colombie\" width=\"300\" height=\"199\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-en-Colombie-300x199.jpg 300w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2012\/10\/Noel-en-Colombie.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-103\" class=\"wp-caption-text\">Illumination des f\u00eates de No\u00ebl en Colombie<\/p><\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Llego la Navidad ! Des terres Mexicaines \u00e0 la Terre de Feu, la tradition de No\u00ebl import\u00e9e par les espagnols et les portugais m\u00e9lange rites catholiques et traditions pr\u00e9colombiennes, le tout dans la bonne humeur avec de la musique omni-pr\u00e9sente, des plats traditionnels et pour beaucoup l\u2019occasion de se retrouver en famille.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[60,1],"tags":[62,71,70],"_links":{"self":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/21"}],"collection":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":10,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"predecessor-version":[{"id":4087,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/21\/revisions\/4087"}],"wp:attachment":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}