{"id":1789,"date":"2013-12-10T18:39:39","date_gmt":"2013-12-10T17:39:39","guid":{"rendered":"http:\/\/www.makila.fr\/blog\/voyage-sur-mesure\/?p=1789"},"modified":"2024-10-22T16:54:36","modified_gmt":"2024-10-22T15:54:36","slug":"angkor-musee-guimet-paris","status":"publish","type":"post","link":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/angkor-musee-guimet-paris\/","title":{"rendered":"Les splendeurs d&rsquo;Angkor sont au mus\u00e9e Guimet"},"content":{"rendered":"<p>Angkor, coeur spirituel du Cambodge ! Ses temples somptueux, ses ruines ancestrales, sa v\u00e9g\u00e9tation centenaire et ses chefs-d&rsquo;oeuvre d&rsquo;art et d&rsquo;architecture. Ce site mill\u00e9naire, class\u00e9 au patrimoine mondial par l&rsquo;UNESCO, est sans conteste l&rsquo;une des merveilles de ce monde.\u00a0Jusqu&rsquo;au 13 janvier 2014 laissez-vous transporter par le <a href=\"http:\/\/www.guimet.fr\/fr\/expositions\/expositions-en-cours\/louis-delaporte-et-le-cambodge-la-naissance-dun-mythe\" target=\"_blank\" rel=\"noopener\" class=\"broken_link\">mus\u00e9e Guimet<\/a>, depuis Paris jusqu&rsquo;au Cambodge, pour d\u00e9couvrir la splendeur du patrimoine khmer.\u00a0Il est des voyages qui commencent bien avant le d\u00e9part. Cette \u00e9poustouflante exposition vous enthousiasmera par sa richesse qui remonte jusqu\u2019aux origines du mythe d\u2019Angkor. Alors direction le Cambodge, \u00e0 seulement quelques pas de la tour Eiffel !\u00a0<!--more--><\/p>\n<div id=\"attachment_1790\" style=\"width: 820px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-17.51.20.png\"><img aria-describedby=\"caption-attachment-1790\" loading=\"lazy\" class=\"size-full wp-image-1790\" title=\"Angkor Vat, Cambodge\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-17.51.20.png\" alt=\"\" width=\"810\" height=\"523\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-17.51.20.png 810w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-17.51.20-300x193.png 300w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/a><p id=\"caption-attachment-1790\" class=\"wp-caption-text\">Angkor Vat, Cambodge<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Angkor, la naissance d&rsquo;un mythe<\/strong><\/p>\n<div id=\"attachment_1793\" style=\"width: 209px\" class=\"wp-caption alignleft\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.19.56.png\"><img aria-describedby=\"caption-attachment-1793\" loading=\"lazy\" class=\"size-medium wp-image-1793\" title=\"Affiche de l'exposition du mus\u00e9e Guimet\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.19.56-199x300.png\" alt=\"\" width=\"199\" height=\"300\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.19.56-199x300.png 199w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.19.56.png 349w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a><p id=\"caption-attachment-1793\" class=\"wp-caption-text\">Affiche de l&rsquo;exposition du mus\u00e9e Guimet<\/p><\/div>\n<p>Le mus\u00e9e Guimet est parvenu \u00e0 r\u00e9unir quelque 250 pi\u00e8ces, pr\u00eat\u00e9es par les plus grandes institutions mondiales. Cette exposition rassemble ainsi des sculptures khm\u00e8res en pierre des Xe-XIIIe si\u00e8cles, des moulages en pl\u00e2tre, des photographies et autres peintures et aquarelles.<\/p>\n<p>Au-del\u00e0 de cette s\u00e9lection exhaustive de pi\u00e8ces historiques, cette exposition aborde la mani\u00e8re dont ce patrimoine khmer a \u00e9t\u00e9 red\u00e9couvert par les Europ\u00e9ens et plus particuli\u00e8rement les Fran\u00e7ais. Au milieu du XIX\u00e8me si\u00e8cle, certains explorateurs\u00a0fascin\u00e9s par l&rsquo;art cambodgien ont fait de ce site d\u00e9sert\u00e9, ce tas de ruines d\u00e9laiss\u00e9es, un v\u00e9ritable mythe. L&rsquo;exposition rend hommage \u00e0 Louis Delaporte, un explorateur fran\u00e7ais ayant jou\u00e9 un r\u00f4le cl\u00e9 dans la r\u00e9novation d&rsquo;Angkor, bien d\u00e9cid\u00e9 \u00e0 \u00ab\u00a0faire entrer l&rsquo;art khmer dans les mus\u00e9es\u00a0\u00bb ! Pari r\u00e9ussi quand on sait que ce site re\u00e7oit aujourd&rsquo;hui plus d&rsquo;un million de visiteurs chaque ann\u00e9e.<\/p>\n<p>On aime tout particuli\u00e8rement la reconstitution, dans la salle khm\u00e8re, d\u2019importantes structures, telle la tour \u00e0 visages du temple du Bayon. Cette exposition donne la pleine mesure du poids de l&rsquo;histoire, de la richesse du patrimoine khmer et donnerait presque&#8230; des <a href=\"http:\/\/www.makila.fr\/voyages\/pays\/42-cambodge\" target=\"_blank\" rel=\"noopener\">id\u00e9es de voyages au Cambodge<\/a> !<\/p>\n<p>Si comme nous, cette exposition vous donne envie de vous rendre sur place, nous avons concoct\u00e9 pour vous, plusieurs voyages\u00a0alliant les richesses culturelles d&rsquo;Angkor au farniente sur les plages de sable blanc.<\/p>\n<p><strong>Visiter le Cambodge, c\u2019est vivre un grand choc culturel<\/strong><\/p>\n<div id=\"attachment_1799\" style=\"width: 688px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.58.17.png\"><img aria-describedby=\"caption-attachment-1799\" loading=\"lazy\" class=\"size-full wp-image-1799\" title=\"Angkor Thom, Cambodge\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.58.17.png\" alt=\"\" width=\"678\" height=\"501\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.58.17.png 678w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-10-\u00e0-18.58.17-300x221.png 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><p id=\"caption-attachment-1799\" class=\"wp-caption-text\">Angkor Thom, Cambodge<\/p><\/div>\n<p>On a con\u00e7u un voyage pour d\u00e9couvrir Angkor :\u00a0<a href=\"http:\/\/www.makila.fr\/voyages\/75-angkor-coeur-spirituel-et-culturel-du-cambodge\" target=\"_blank\" rel=\"noopener\">plong\u00e9e<\/a> au coeur des innombrables monuments de l\u2019apog\u00e9e de l\u2019art Khmer : Angkor Thom, les temples de Ta Keo, de Bantey Srei et du monast\u00e8re de Ta Prohm recouvert par la jungle, tout en vous reposant au bord de la piscine de l&rsquo;h\u00f4tel <a href=\"http:\/\/www.makila.fr\/hotels\/633-la-palmeraie\" target=\"_blank\" rel=\"noopener\">La Palmeraie<\/a>.<\/p>\n<div id=\"attachment_1802\" style=\"width: 403px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.01.32.png\"><img aria-describedby=\"caption-attachment-1802\" loading=\"lazy\" class=\"size-full wp-image-1802\" title=\"Angkor, Cambodge\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.01.32.png\" alt=\"\" width=\"393\" height=\"530\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.01.32.png 393w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.01.32-222x300.png 222w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/a><p id=\"caption-attachment-1802\" class=\"wp-caption-text\">Angkor, Cambodge<\/p><\/div>\n<p>Id\u00e9al en couple ou entre amis, la d\u00e9couverte de la fascinante culture cambodgienne se fait aussi <a href=\"http:\/\/www.makila.fr\/voyages\/176-le-cambodge-en-famille\" target=\"_blank\" rel=\"noopener\">en famille<\/a> ! Angkor \u00e0 tuk-tuk, les mangroves de Koh Kong en kayak\u2026Petits comme grands vont adorer cette destination captivante et peu connue.<\/p>\n<p>Vous serez sous le charme de cette population cambodgienne si accueillante, ainsi que des paysages majestueux. Que ce soit les temples de Tah Phrom, Sambor Prei Kuk ou encore les superbes balades \u00e0 v\u00e9lo sur l\u2019\u00eele d\u2019Oknhatey, vous construirez ensemble des souvenirs inoubliables.<\/p>\n<div id=\"attachment_1803\" style=\"width: 405px\" class=\"wp-caption aligncenter\"><a href=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.31.04.png\"><img aria-describedby=\"caption-attachment-1803\" loading=\"lazy\" class=\"size-full wp-image-1803\" title=\"Enfants du Cambodge\" src=\"\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.31.04.png\" alt=\"\" width=\"395\" height=\"531\" srcset=\"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.31.04.png 395w, https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-content\/uploads\/2013\/12\/Capture-d\u2019\u00e9cran-2013-12-11-\u00e0-10.31.04-223x300.png 223w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/><\/a><p id=\"caption-attachment-1803\" class=\"wp-caption-text\">Enfants du Cambodge<\/p><\/div>\n<p>&nbsp;<\/p>\n<div>Alors, tent\u00e9s par une petite escapade dans la magie d&rsquo;Angkor ? En attendant&#8230; il vous reste encore un mois pour d\u00e9couvrir l&rsquo;exposition du <a href=\"https:\/\/maps.google.com\/maps?ie=UTF-8&amp;q=mus%C3%A9e+guimet&amp;fb=1&amp;hq=mus%C3%A9e+guimet+paris&amp;cid=13108857093538749577&amp;ei=5mCwUqvLDMer0gWb5oHAAg&amp;ved=0CLABEPwS\" target=\"_blank\" rel=\"noopener\">mus\u00e9e Guimet<\/a> !<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Angkor, coeur spirituel du Cambodge ! Ses temples somptueux, ses ruines ancestrales, sa v\u00e9g\u00e9tation centenaire et ses chefs-d&rsquo;oeuvre d&rsquo;art et d&rsquo;architecture. Ce site mill\u00e9naire, class\u00e9 au patrimoine mondial par l&rsquo;UNESCO, est sans conteste l&rsquo;une des merveilles de ce monde.\u00a0Jusqu&rsquo;au 13 janvier 2014 laissez-vous transporter par le mus\u00e9e Guimet, depuis Paris jusqu&rsquo;au Cambodge, pour d\u00e9couvrir la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[60,1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/1789"}],"collection":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":27,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"predecessor-version":[{"id":4101,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/posts\/1789\/revisions\/4101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media\/1790"}],"wp:attachment":[{"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.makila.fr\/voyage-sur-mesure\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}